{"id":1731,"date":"2021-12-17T13:40:07","date_gmt":"2021-12-17T16:40:07","guid":{"rendered":"http:\/\/www.institutoliberdadedigital.com.br\/site\/?p=1731"},"modified":"2021-12-17T13:40:12","modified_gmt":"2021-12-17T16:40:12","slug":"newsletter-edicao-17-12-2021","status":"publish","type":"post","link":"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/","title":{"rendered":"Newsletter &#8211; Edi\u00e7\u00e3o 17.12.2021"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img src=\"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/12\/NEWSLETTER-CAPA-5.png\" alt=\"\" class=\"wp-image-1732\" width=\"1236\" height=\"480\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img width=\"810\" height=\"100\" src=\"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/2.png\" alt=\"O atributo alt desta imagem est\u00e1 vazio. O nome do arquivo \u00e9 2.png\" class=\"wp-image-1596\" srcset=\"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/2.png 810w, http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/2-600x74.png 600w, http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/2-768x95.png 768w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<h4 class=\"has-very-dark-gray-color has-text-color\"><strong><strong><strong><strong><strong><strong><strong><strong><strong>At\u00e9 onde a desvaloriza\u00e7\u00e3o da arte no Brasil pode ser um gatilho para a liberdade de express\u00e3o?<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h4>\n\n\n\n<p>Ap\u00f3s a acusa\u00e7\u00e3o feita pela mobile (Movimento Brasileiro Integrado pela Liberdade de Express\u00e3o Art\u00edstica), foi apresentada nesta ter\u00e7a-feira (14) pela Comiss\u00e3o Interamericana de Direitos Humanos, uma <a href=\"https:\/\/www1.folha.uol.com.br\/opiniao\/2021\/12\/liberdade-de-expressao-artistica-solta-a-voz-na-oea.shtml\">audi\u00eancia p\u00fablica a fim de ouvir den\u00fancias e experi\u00eancias que levam a viola\u00e7\u00e3o dos direitos de liberdade de express\u00e3o art\u00edstica<\/a>, devido a persegui\u00e7\u00e3o a artistas e as suas artes. Como participantes, contando suas pr\u00f3prias viv\u00eancias, foram convocados os artistas Caetano Veloso (que compartilhou o momento em que foi preso junto com Gilberto Gil ap\u00f3s a repress\u00e3o trazida com o AI-5), Wagner Moura (que evidenciou sua dificuldade em estrear Marighella durante o governo atual, por conta do enredo do filme) e Daniela Mercury ( que afirmou a exist\u00eancia de\u00a0 um tipo in\u00e9dito de censura nesse momento do Brasil).<\/p>\n\n\n\n<p>Os artistas que acusam o governo atual de ataques \u00e0 democracia, partem da mesma premissa de frisar a import\u00e2ncia do investimento em projetos culturais que impactam tamb\u00e9m diretamente nos direitos humanos, indo contra qualquer tipo de censura. Pois restringindo o acesso a essas verbas, n\u00e3o \u00e9 apenas o direito do artista de se expressar livremente que seria afetado, mas tamb\u00e9m a contribui\u00e7\u00e3o de todo o corpo do projeto e o acesso \u00e0 cultura que deveria estar presente em todo o lugar. <a href=\"https:\/\/gauchazh.clicrbs.com.br\/cultura-e-lazer\/noticia\/2021\/12\/caetano-veloso-wagner-moura-e-daniela-mercury-participam-de-audiencia-internacional-sobre-censura-no-brasil-ckx7n6x7a003t014cm4ldeakx.html\">Para os artistas citados, a democracia deve andar junto com a liberdade, e para tanto, tanto\u00a0 a estrutura estatal\u00a0 quanto a harmonia entre as autoridades e a sociedade, importam para que isso funcione.<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"has-very-dark-gray-color has-text-color has-text-align-right\"><strong><strong><strong><strong><strong><strong><strong>H\u00e1\u00a0 diferentes concep\u00e7\u00f5es de democracia para Bolsonaro, dentro e fora de casa<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h4>\n\n\n\n<p>Com a participa\u00e7\u00e3o de mais de 100 pa\u00edses na C\u00fapula convocada por Biden, <a href=\"https:\/\/brasil.elpais.com\/brasil\/2021-12-10\/imagem-internacional-autoritaria-e-entrave-para-discurso-moderado-de-bolsonaro-na-cupula-pela-democracia.html\">Bolsonaro defendeu a democracia e garantiu que o Brasil \u00e9\u00a0 importante para o fortalecimento democr\u00e1tico no mundo<\/a>, atrav\u00e9s da liberdade de express\u00e3o e da valoriza\u00e7\u00e3o dos direitos humanos. O discurso surpreendeu alguns membros da sociedade que apontam incoer\u00eancia da fala do Presidente\u00a0 com suas a\u00e7\u00f5es no combate de not\u00edcias falsas, nos ataques \u00e0 imprensa\u00a0 e na edi\u00e7\u00e3o do decreto de sigilo de informa\u00e7\u00f5es sobre ele e seus filhos.<\/p>\n\n\n\n<p>Em seu discurso gravado, o presidente do Brasil assegurou a valoriza\u00e7\u00e3o do direito de todos serem livres e poderem expressar suas opini\u00f5es na internet. <a href=\"https:\/\/valor.globo.com\/politica\/noticia\/2021\/12\/10\/bolsonaro-estamos-empenhados-em-assegurar-liberdade-de-expressao-inclusive-na-internet.ghtml\">Por\u00e9m, analistas pol\u00edticos relativizam o impacto da declara\u00e7\u00e3o em raz\u00e3o do cen\u00e1rio de ataques \u00e0 democracia<\/a>, direitos humanos e prote\u00e7\u00f5es ao meio ambiente, a vis\u00e3o internacional em rela\u00e7\u00e3o ao Brasil pode estar\u00a0 comprometida.\u00a0<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large\"><img width=\"810\" height=\"100\" src=\"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/4.png\" alt=\"\" class=\"wp-image-1597\" srcset=\"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/4.png 810w, http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/4-600x74.png 600w, http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/4-768x95.png 768w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"color:#fdfdfd\" class=\"has-text-color\">jnjj<\/p>\n\n\n\n<h1 class=\"has-text-color has-text-align-right\" style=\"color:#fdfdfd\">teste<\/h1>\n\n\n\n<p style=\"color:#ffffff\" class=\"has-text-color\">jnjj<\/p>\n\n\n\n<h4 class=\"has-very-dark-gray-color has-text-color has-text-align-left\"><strong><strong><strong><strong><strong><strong><strong>PL 2303\/15 e novo respaldo legal do cripto mercado<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h4>\n\n\n\n<p><a href=\"https:\/\/www.camara.leg.br\/noticias\/836731-camara-aprova-projeto-que-preve-regras-para-negociacao-de-moedas-virtuais\/\">A C\u00e2mara dos Deputados aprovou nesta quarta-feira (8) o Projeto de Lei 2303\/15, que prev\u00ea a regulamenta\u00e7\u00e3o por parte do governo federal, na presta\u00e7\u00e3o de servi\u00e7os de ativos digitais.<\/a> O deputado Expedito Netto, afirma que \u201co projeto defende a moeda digital e pretende tornar esse mercado mais seguro e amplo, valorizando o investimento\u201d. Por ser um projeto parlamentar, o deputado n\u00e3o p\u00f4de afirmar explicitamente se o \u00f3rg\u00e3o regulador ser\u00e1 o banco central, mas \u00e9 esperado que esse seja o indicado pelo executivo.<\/p>\n\n\n\n<p><a href=\"https:\/\/www12.senado.leg.br\/noticias\/audios\/2021\/12\/especialistas-analisam-proposta-de-regulacao-do-mercado-de-criptomoedas\">O PL 2303\/15 segue a fun\u00e7\u00e3o de cobrir legalmente, parte do cripto mercado que antes n\u00e3o era respaldado<\/a>, mercado esse que existe no Brasil com altos volumes de trocas, Juliana Facklmann, representante da plataforma Mercado Bitcoin, afirma que a plataforma \u00e9 a maior da Am\u00e9rica Latina, e opera no Brasil desde 2013. Apenas no \u00faltimo ano, o site movimentou mais de R$40 bilh\u00f5es.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"has-very-dark-gray-color has-text-color has-text-align-right\"><strong>IA e suas oportunidades de crescimento humano<\/strong><\/h4>\n\n\n\n<p><a href=\"https:\/\/valor.globo.com\/carreira\/noticia\/2021\/12\/06\/inteligencia-artificial-pode-ajudar-a-formar-superprofissionais.ghtml\">Estudo realizado pelo MIT <\/a>(Instituto de Tecnologia de Massachusetts), mostrou como a utiliza\u00e7\u00e3o de IA por empresas e seus times, aumentaram diferentes avalia\u00e7\u00f5es, como melhoria de desempenho em tomadas de decis\u00e3o, melhorias no processo de aprendizagem e a confian\u00e7a da pr\u00f3pria equipe. Alguns dos desafios mais apontados foram a falta de conhecimento sobre o funcionamento da IA, assim como a falta de treinamentos, mas que superados os obst\u00e1culos, os resultados eram positivos.<\/p>\n\n\n\n<p>Os avan\u00e7os e o grau de utiliza\u00e7\u00e3o de IA podem aumentar ainda mais. Tamb\u00e9m do MIT, um estudante prod\u00edgio, Arnav Kapur, ajudou a desenvolver uma tecnologia de IA nomeada de Alter Ego, que possibilita a aplica\u00e7\u00e3o de comandos digitais apenas com nossos pensamentos, atrav\u00e9s de um \u201c<em>headset<\/em>\u201d que conecta a IA e nossa atividade cerebral.<a href=\"https:\/\/valor.globo.com\/carreira\/noticia\/2021\/12\/06\/inteligencia-artificial-pode-ajudar-a-formar-superprofissionais.ghtml\"> Aplica\u00e7\u00f5es podem variar desde uma nova ferramenta de fala para pacientes com a fala danificada,<\/a> at\u00e9 extens\u00f5es de esta\u00e7\u00f5es de trabalho, entre muitos outros benef\u00edcios para aprendizagem e profissionaliza\u00e7\u00e3o.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img src=\"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/6.png\" alt=\"\" class=\"wp-image-1598\" width=\"580\" height=\"71\" srcset=\"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/6.png 810w, http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/6-600x74.png 600w, http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/6-768x95.png 768w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><\/figure>\n\n\n\n<h4 class=\"has-very-dark-gray-color has-text-color\">PL das Fake News \u00e9 alvo de cr\u00edticas do mercado publicit\u00e1rio<\/h4>\n\n\n\n<p>Ap\u00f3s intenso vai e vem, <a href=\"https:\/\/www.camara.leg.br\/noticias\/836267-grupo-da-camara-conclui-votacao-de-relatorio-sobre-combate-as-fake-news\/\">o PL das Fake News foi aprovado no Grupo de Trabalho da C\u00e2mara dos Deputados<\/a>. Assim, a expectativa do relator do referido projeto, Deputado Federal Orlando Silva (PCdoB-SP) \u00e9 de que a proposta seja inclu\u00edda na pauta para aprecia\u00e7\u00e3o do Plen\u00e1rio.<\/p>\n\n\n\n<p>Contudo, a iniciativa do legislativo tem sofrido mais uma resist\u00eancia. <a href=\"https:\/\/jovempan.com.br\/programas\/jornal-da-manha\/empresas-de-publicidade-digital-fazem-pressao-contra-o-pl-das-fake-news.html\">Ag\u00eancias e grupos de comunica\u00e7\u00e3o t\u00eam se articulado para promover um abaixo-assinado<\/a>, alegando que o projeto promove o fim da publicidade digital a partir das veda\u00e7\u00e3o de compartilhamento de dados entre as redes e demais empresas, al\u00e9m de determinar que os provedores publiquem todos os conte\u00fados impulsionados para propaganda eleitoral. Ainda assim, vale ressaltar que o PL se sujeitou a intenso debate e que h\u00e1 especialistas que, em contrapartida, entendem que as disposi\u00e7\u00f5es da proposta promovem a transpar\u00eancia e maior prote\u00e7\u00e3o dos dados dos usu\u00e1rios das plataformas digitais.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"has-very-dark-gray-color has-text-color has-text-align-right\"><strong><strong>Brasil e um pioneirismo necess\u00e1rio<\/strong><\/strong><\/h4>\n\n\n\n<p><a href=\"https:\/\/www.tse.jus.br\/imprensa\/noticias-tse\/2021\/Dezembro\/tse-aprova-quatro-resolucoes-com-regras-para-as-eleicoes-2022\">A partir da sexta-feira (10), posts nas plataformas sob a bandeira Meta (antigo Facebook) que hoje incluem Facebook e Instagram, que forem identificados como de pauta eleitoral, ir\u00e3o possuir um selo com link diretamente para o Portal de Justi\u00e7a Eleitoral<\/a>, como meio de combate \u00e0 propaga\u00e7\u00e3o de fake news e evitar influ\u00eancia no pleito. Essa medida se apresentou de\u00a0 forma similar em outras plataformas quando o assunto era COVID e a pandemia, direcionando os leitores para sites de informa\u00e7\u00e3o de estudos pela Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) e da Alian\u00e7a Global de Vacinas (Gavi). O Brasil ser\u00e1 o primeiro pa\u00eds a receber esse tratamento aplicado ao processo eleitoral, fruto da parceria do TSE com Facebook e Instagram.<\/p>\n\n\n\n<p>Mais movimenta\u00e7\u00f5es podem ser vistas para regular o pleito de 2022.\u00a0 O ministro Edson Fachin, r<a href=\"https:\/\/www.tse.jus.br\/imprensa\/noticias-tse\/2021\/Dezembro\/tse-aprova-quatro-resolucoes-com-regras-para-as-eleicoes-2022\">elator de audi\u00eancias p\u00fablicas nos dias 22 e 23 de novembro, recebeu sugest\u00f5es dos partidos para melhoria do processo eleitoral de 2022<\/a>, e nesse momento afirmou que \u201cTais sugest\u00f5es muito contribu\u00edram para o aperfei\u00e7oamento das minutas\u201d, tendo pautas como fundo eleitoral, presta\u00e7\u00e3o de contas, atos gerais do processo eleitoral e cadastro de eleitores. O Ministro Lu\u00eds Roberto Barroso afirmou que as resolu\u00e7\u00f5es apenas regulamentam a legisla\u00e7\u00e3o adotada anteriormente pelo Congresso Nacional, com o intuito de tornar as regras mais claras e objetivas.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img width=\"810\" height=\"100\" src=\"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/8.png\" alt=\"O atributo alt desta imagem est\u00e1 vazio. O nome do arquivo \u00e9 8.png\" class=\"wp-image-1599\" srcset=\"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/8.png 810w, http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/8-600x74.png 600w, http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/09\/8-768x95.png 768w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure><\/div>\n\n\n\n<h4 class=\"has-very-dark-gray-color has-text-color has-text-align-center\"><strong><strong><strong><strong><strong><strong>Voc\u00ea sabia que o ILD tem um podcast?<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h4>\n\n\n\n<p>E o epis\u00f3dio <a href=\"https:\/\/open.spotify.com\/episode\/0vWusDq4X8RvQU08F50GJ8?si=MwG3GI5sRFGGiePDl9sy0Q\">#20 <\/a>do <strong>#podcastdoILD<\/strong> j\u00e1 est\u00e1 no ar! Comandado pelos professores Diogo Rais e Marco Sabino, o assunto da vez \u00e9: <strong>Tem liberdade na publicidade? <\/strong>Todos os epis\u00f3dios est\u00e3o dispon\u00edveis em 7 plataformas diferentes: Anchor, Breaker, Google Podcasts, Pocket Casts, Radio Public e Spotify e, agora, tamb\u00e9m no Youtube!<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h4 class=\"has-text-align-center\">O Instituto Liberdade Digital deseja boas festas e um excelente 2022!<\/h4>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><strong>Esta newsletter faz parte do projeto Observat\u00f3rio Eleitoral Digital do Instituto Liberdade Digital e contou com a participa\u00e7\u00e3o da equipe do Instituto: Alinne Lopes, Ana J\u00falia Bernardi, Camila Tsuzuki, Giovanna Guilhem, Cain\u00e3 Oliveira, Julia Damaci, Rachel da Mota, Maria Marinho e Roberta Battisti.<\/strong><\/p>\n\n\n\n<p><strong>O que achou da nossa Newsletter? Caso tenha coment\u00e1rios, observa\u00e7\u00f5es ou outra vers\u00e3o do que veiculamos aqui, nos envie um e-mail: contato@institutoliberdadedigital.com.br. Todos os feedbacks s\u00e3o bem-vindos!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vem conferir as novidades do Direito Eleitoral Digital das \u00faltimas semanas!<\/p>\n","protected":false},"author":5,"featured_media":1733,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Newsletter - Edi\u00e7\u00e3o 17.12.2021 - Instituto Liberdade Digital<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Newsletter - Edi\u00e7\u00e3o 17.12.2021 - Instituto Liberdade Digital\" \/>\n<meta property=\"og:description\" content=\"Vem conferir as novidades do Direito Eleitoral Digital das \u00faltimas semanas!\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto Liberdade Digital\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Institutoliberdadedigital\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-17T16:40:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-17T16:40:12+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/12\/NEWSLETTER-CAPA-5-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"312\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Instituto Liberdade Digital\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@InstitutoLD\" \/>\n<meta name=\"twitter:site\" content=\"@InstitutoLD\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Instituto Liberdade Digital\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/\"},\"author\":{\"name\":\"Instituto Liberdade Digital\",\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/#\/schema\/person\/3402282a756f23a7f91e46715a2897ca\"},\"headline\":\"Newsletter &#8211; Edi\u00e7\u00e3o 17.12.2021\",\"datePublished\":\"2021-12-17T16:40:07+00:00\",\"dateModified\":\"2021-12-17T16:40:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/\"},\"wordCount\":1346,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/#organization\"},\"articleSection\":[\"PROJETOS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/\",\"url\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/\",\"name\":\"Newsletter - Edi\u00e7\u00e3o 17.12.2021 - Instituto Liberdade Digital\",\"isPartOf\":{\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/#website\"},\"datePublished\":\"2021-12-17T16:40:07+00:00\",\"dateModified\":\"2021-12-17T16:40:12+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsletter &#8211; Edi\u00e7\u00e3o 17.12.2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/#website\",\"url\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/\",\"name\":\"Instituto Liberdade Digital\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/#organization\",\"name\":\"Instituto Liberdade Digital\",\"url\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/\",\"sameAs\":[\"https:\/\/instagram.com\/institutoliberdadedigital?igshid=1xyjdem24x4db\",\"https:\/\/www.linkedin.com\/company\/institutoliberdadedigital\",\"https:\/\/www.youtube.com\/channel\/UCWxG8jDEsVd9ikHEzlHnhxw\",\"https:\/\/www.facebook.com\/Institutoliberdadedigital\/\",\"https:\/\/twitter.com\/InstitutoLD\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/10\/logotipo-big.png\",\"contentUrl\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/10\/logotipo-big.png\",\"width\":1080,\"height\":1080,\"caption\":\"Instituto Liberdade Digital\"},\"image\":{\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/#\/schema\/person\/3402282a756f23a7f91e46715a2897ca\",\"name\":\"Instituto Liberdade Digital\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/0eff6e6f9446d909073aa9cbda4e605d?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/0eff6e6f9446d909073aa9cbda4e605d?s=96&d=mm&r=g\",\"caption\":\"Instituto Liberdade Digital\"},\"url\":\"http:\/\/www.institutoliberdadedigital.com.br\/site\/author\/gerenciador\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Newsletter - Edi\u00e7\u00e3o 17.12.2021 - Instituto Liberdade Digital","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/","og_locale":"pt_BR","og_type":"article","og_title":"Newsletter - Edi\u00e7\u00e3o 17.12.2021 - Instituto Liberdade Digital","og_description":"Vem conferir as novidades do Direito Eleitoral Digital das \u00faltimas semanas!","og_url":"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/","og_site_name":"Instituto Liberdade Digital","article_publisher":"https:\/\/www.facebook.com\/Institutoliberdadedigital\/","article_published_time":"2021-12-17T16:40:07+00:00","article_modified_time":"2021-12-17T16:40:12+00:00","og_image":[{"width":820,"height":312,"url":"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/12\/NEWSLETTER-CAPA-5-1.png","type":"image\/png"}],"author":"Instituto Liberdade Digital","twitter_card":"summary","twitter_creator":"@InstitutoLD","twitter_site":"@InstitutoLD","twitter_misc":{"Escrito por":"Instituto Liberdade Digital","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/#article","isPartOf":{"@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/"},"author":{"name":"Instituto Liberdade Digital","@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/#\/schema\/person\/3402282a756f23a7f91e46715a2897ca"},"headline":"Newsletter &#8211; Edi\u00e7\u00e3o 17.12.2021","datePublished":"2021-12-17T16:40:07+00:00","dateModified":"2021-12-17T16:40:12+00:00","mainEntityOfPage":{"@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/"},"wordCount":1346,"commentCount":0,"publisher":{"@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/#organization"},"articleSection":["PROJETOS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/","url":"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/","name":"Newsletter - Edi\u00e7\u00e3o 17.12.2021 - Instituto Liberdade Digital","isPartOf":{"@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/#website"},"datePublished":"2021-12-17T16:40:07+00:00","dateModified":"2021-12-17T16:40:12+00:00","breadcrumb":{"@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/2021\/12\/newsletter-edicao-17-12-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/www.institutoliberdadedigital.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Newsletter &#8211; Edi\u00e7\u00e3o 17.12.2021"}]},{"@type":"WebSite","@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/#website","url":"http:\/\/www.institutoliberdadedigital.com.br\/site\/","name":"Instituto Liberdade Digital","description":"","publisher":{"@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.institutoliberdadedigital.com.br\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/#organization","name":"Instituto Liberdade Digital","url":"http:\/\/www.institutoliberdadedigital.com.br\/site\/","sameAs":["https:\/\/instagram.com\/institutoliberdadedigital?igshid=1xyjdem24x4db","https:\/\/www.linkedin.com\/company\/institutoliberdadedigital","https:\/\/www.youtube.com\/channel\/UCWxG8jDEsVd9ikHEzlHnhxw","https:\/\/www.facebook.com\/Institutoliberdadedigital\/","https:\/\/twitter.com\/InstitutoLD"],"logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/#\/schema\/logo\/image\/","url":"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/10\/logotipo-big.png","contentUrl":"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-content\/uploads\/2021\/10\/logotipo-big.png","width":1080,"height":1080,"caption":"Instituto Liberdade Digital"},"image":{"@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/#\/schema\/person\/3402282a756f23a7f91e46715a2897ca","name":"Instituto Liberdade Digital","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"http:\/\/www.institutoliberdadedigital.com.br\/site\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/0eff6e6f9446d909073aa9cbda4e605d?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/0eff6e6f9446d909073aa9cbda4e605d?s=96&d=mm&r=g","caption":"Instituto Liberdade Digital"},"url":"http:\/\/www.institutoliberdadedigital.com.br\/site\/author\/gerenciador\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-json\/wp\/v2\/posts\/1731"}],"collection":[{"href":"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-json\/wp\/v2\/comments?post=1731"}],"version-history":[{"count":2,"href":"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-json\/wp\/v2\/posts\/1731\/revisions"}],"predecessor-version":[{"id":1735,"href":"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-json\/wp\/v2\/posts\/1731\/revisions\/1735"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-json\/wp\/v2\/media\/1733"}],"wp:attachment":[{"href":"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-json\/wp\/v2\/media?parent=1731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-json\/wp\/v2\/categories?post=1731"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.institutoliberdadedigital.com.br\/site\/wp-json\/wp\/v2\/tags?post=1731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}